{"id":1325,"date":"2013-09-13T04:23:09","date_gmt":"2013-09-13T04:23:09","guid":{"rendered":"http:\/\/www.encontrapelotas.com.br\/noticias\/?p=1325"},"modified":"2013-09-13T04:23:09","modified_gmt":"2013-09-13T04:23:09","slug":"exposicao-de-ceramicas-e-gravuras-japonesas-e-atracao-em-pelotas","status":"publish","type":"post","link":"https:\/\/www.encontrapelotas.com.br\/noticias\/exposicao-de-ceramicas-e-gravuras-japonesas-e-atracao-em-pelotas\/","title":{"rendered":"Exposi\u00e7\u00e3o de Cer\u00e2micas e Gravuras Japonesas \u00e9 atra\u00e7\u00e3o em Pelotas"},"content":{"rendered":"<p>O Museu de Arte Leopoldo Gotuzzo (Malg) lan\u00e7ou nesta quinta-feira (12\/09\/2013), a exposi\u00e7\u00e3o de Cer\u00e2micas e Gravuras Japonesas da cole\u00e7\u00e3o de Luiz Carlos Lessa Vinholes.<\/p>\n<p>A mostra \u00e9 uma homenagem aos 50 anos da rela\u00e7\u00e3o de irmandade entre Pelotas e Suzu, as primeiras cidades-irm\u00e3s entre Brasil e Jap\u00e3o.<\/p>\n<p>As obras foram reunidas durante d\u00e9cadas pelo artista pelotense que viveu no Jap\u00e3o durante anos, atuando como encarregado de assuntos culturais da embaixada brasileira. A partir desta exposi\u00e7\u00e3o, as pe\u00e7as passar\u00e3o a integrar o acervo do Malg definitivamente, pela doa\u00e7\u00e3o de Vinholes.<\/p>\n<p>O diretor de Artes Visuais da Secretaria Municipal de Cultura (Secult) Giorgio Ronna destaca a import\u00e2ncia desta exposi\u00e7\u00e3o n\u00e3o apenas pelo seu valor est\u00e9tico, mas pelo cunho hist\u00f3rico. \u201cAs obras nip\u00f4nicas do s\u00e9culo 19, que foram doadas ao Malg, serviram de inspira\u00e7\u00e3o para grandes artistas europeus como Van Gogh e Edgar Degas. E agora est\u00e3o dispon\u00edveis n\u00e3o s\u00f3 para aprecia\u00e7\u00e3o do p\u00fablico, mas tamb\u00e9m para fonte de estudo dos artistas locais\u201d.<\/p>\n<p>A visita\u00e7\u00e3o ser\u00e1 do dia 13 de setembro ao dia 3 de novembro de 2013, das 10h \u00e0s 19h, com entrada franca, \u00e0 rua General Os\u00f3rio, 725.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Museu de Arte Leopoldo Gotuzzo (Malg) lan\u00e7ou nesta quinta-feira (12\/09\/2013), a exposi\u00e7\u00e3o de Cer\u00e2micas e Gravuras Japonesas da cole\u00e7\u00e3o de Luiz Carlos Lessa Vinholes. A mostra \u00e9 uma homenagem aos 50 anos da rela\u00e7\u00e3o de irmandade entre Pelotas e Suzu, as primeiras cidades-irm\u00e3s entre Brasil e Jap\u00e3o. As obras foram reunidas durante d\u00e9cadas pelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1325","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"predecessor-version":[{"id":1326,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1325\/revisions\/1326"}],"wp:attachment":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}