{"id":339,"date":"2012-08-15T08:00:16","date_gmt":"2012-08-15T08:00:16","guid":{"rendered":"http:\/\/www.encontrapelotas.com.br\/noticias\/?p=339"},"modified":"2013-08-16T14:17:03","modified_gmt":"2013-08-16T14:17:03","slug":"pelotas-smcas-faz-doacao-de-papel-para-a-escola-louis-braille","status":"publish","type":"post","link":"https:\/\/www.encontrapelotas.com.br\/noticias\/pelotas-smcas-faz-doacao-de-papel-para-a-escola-louis-braille\/","title":{"rendered":"Pelotas: SMCAS faz doa\u00e7\u00e3o de papel para a Escola Louis Braille"},"content":{"rendered":"<p>A Secretaria de Cidadania e Assist\u00eancia Social (SMCAS) realizou, na manh\u00e3 de segunda-feira (13), a doa\u00e7\u00e3o de folhas de papel continuas para a Escola Louis Braille, com o objetivo de adaptar o material para a utiliza\u00e7\u00e3o dos alunos.<\/p>\n<p>Com o material tamb\u00e9m ser\u00e1 elaborada a confec\u00e7\u00e3o de 300 cartilhas da Lei Maria da Penha em Braille, que ter\u00e1 a fun\u00e7\u00e3o de informar os alunos, a popula\u00e7\u00e3o e, principalmente, as mulheres com defici\u00eancia visual, que v\u00e3o ter acesso \u00e0s informa\u00e7\u00f5es referentes \u00e0 Lei.<\/p>\n<p>\u201cO kit com a cartilha e um CD de \u00e1udio dever\u00e3o ser distribu\u00eddos a partir do final do m\u00eas de setembro, em locais indicados pelos parceiros e alguns munic\u00edpios vizinhos\u201d, explicou o chefe de gabinete da SMCAS, Gustavo Zaltron.<\/p>\n<p>A iniciativa faz parte da parceria realizada entre Secretarias de Cidadania e Assist\u00eancia Social, Igualdade Social, Delegacia da Mulher, R\u00e1dio Universidade Cat\u00f3lica de Pelotas e a Escola Louis Braille, que \u00e9 respons\u00e1vel por organizar o material.<\/p>\n<p><em>Fonte: Prefeitura Municipal de Pelotas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Cidadania e Assist\u00eancia Social (SMCAS) realizou, na manh\u00e3 de segunda-feira (13), a doa\u00e7\u00e3o de folhas de papel continuas para a Escola Louis Braille, com o objetivo de adaptar o material para a utiliza\u00e7\u00e3o dos alunos. Com o material tamb\u00e9m ser\u00e1 elaborada a confec\u00e7\u00e3o de 300 cartilhas da Lei Maria da Penha em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[15],"class_list":["post-339","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-pelotas"],"_links":{"self":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":2,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":1159,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/339\/revisions\/1159"}],"wp:attachment":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}