{"id":844,"date":"2013-05-17T14:35:02","date_gmt":"2013-05-17T14:35:02","guid":{"rendered":"http:\/\/www.encontrapelotas.com.br\/noticias\/?p=844"},"modified":"2013-08-16T14:17:00","modified_gmt":"2013-08-16T14:17:00","slug":"pelotas-sdet-e-sgmu-se-reunem-com-dnit","status":"publish","type":"post","link":"https:\/\/www.encontrapelotas.com.br\/noticias\/pelotas-sdet-e-sgmu-se-reunem-com-dnit\/","title":{"rendered":"Pelotas: Sdet e SGMU se re\u00fanem com DNIT"},"content":{"rendered":"<p>O secret\u00e1rio de Desenvolvimento Econ\u00f4mico e Turismo Fernando Estima, acompanhado da secret\u00e1ria de Gest\u00e3o da Cidade e Mobilidade Urbana Joseane Almeida, reuniu-se, na manh\u00e3 de hoje (16), na sede do Departamento Nacional de Infraestrutura de Transportes (DNIT), em Pelotas, com o engenheiro Vladimir Casa, para a discuss\u00e3o de uma s\u00e9rie de fatores que envolvem o entorno da BR 116.<\/p>\n<p>O encontro abordou, mais especificamente, a obra de duplica\u00e7\u00e3o da rodovia, em especial no trecho que compreende a r\u00f3tula do Centro de Eventos Fenadoce, para tratar das obras de acesso a um hotel da rede \u00cdbis, que ser\u00e1 constru\u00eddo naquela \u00e1rea.<\/p>\n<p>O empreendimento Eixo Sul \u2013 Plataforma Log\u00edstica e Empresarial, a ser constru\u00eddo em \u00e1rea de 100 hectares, na BR-116, do lado esquerdo, sentido Pelotas\/Turu\u00e7u, tamb\u00e9m foi pauta do encontro, em que se discutiu os acessos ao local, entre outras demandas do empreendimento.<\/p>\n<p>A reuni\u00e3o ainda tratou do acesso ao Porto da cidade de Pelotas, discutindo outra alternativa de entrada dos caminh\u00f5es ao local, para que n\u00e3o precisem passar por dentro da cidade.<\/p>\n<p>Estima destacou a lideran\u00e7a e o empenho de Casa nas demandas referentes \u00e0 log\u00edstica na \u00e1rea de transportes, ressaltando, tamb\u00e9m, a participa\u00e7\u00e3o da titular da SGMU, nas quest\u00f5es abordadas. \u201c\u00c9 muito importante a presen\u00e7a da secret\u00e1ria Joseane nessas discuss\u00f5es, pois ela tem um olhar diferenciado para onde a cidade quer crescer\u201d, disse.<\/p>\n<p>Tamb\u00e9m participaram do evento na cidade Pelotas, o superintendente da SGMU Guto King e o assessor do Programa Cidade Bem Cuidada Paulo Morales.<\/p>\n<p><em>Fonte: Prefeitura Pelotas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio de Desenvolvimento Econ\u00f4mico e Turismo Fernando Estima, acompanhado da secret\u00e1ria de Gest\u00e3o da Cidade e Mobilidade Urbana Joseane Almeida, reuniu-se, na manh\u00e3 de hoje (16), na sede do Departamento Nacional de Infraestrutura de Transportes (DNIT), em Pelotas, com o engenheiro Vladimir Casa, para a discuss\u00e3o de uma s\u00e9rie de fatores que envolvem o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-844","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=844"}],"version-history":[{"count":4,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/844\/revisions"}],"predecessor-version":[{"id":1090,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/844\/revisions\/1090"}],"wp:attachment":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}