{"id":886,"date":"2013-06-21T01:37:31","date_gmt":"2013-06-21T01:37:31","guid":{"rendered":"http:\/\/www.encontrapelotas.com.br\/noticias\/?p=886"},"modified":"2013-06-20T18:38:16","modified_gmt":"2013-06-20T18:38:16","slug":"receita-federal-doa-veiculos-a-prefeitura-de-pelotas","status":"publish","type":"post","link":"https:\/\/www.encontrapelotas.com.br\/noticias\/receita-federal-doa-veiculos-a-prefeitura-de-pelotas\/","title":{"rendered":"Receita Federal doa ve\u00edculos \u00e0 prefeitura de Pelotas"},"content":{"rendered":"<p>A Receita Federal de Pelotas doou dois \u00f4nibus para a prefeitura de Pelotas. O termo de doa\u00e7\u00e3o foi formalizado no final da tarde da \u00faltima ter\u00e7a-feira (18), entre o prefeito Eduardo Leite e o delegado do \u00f3rg\u00e3o Ricardo de Souza Moreira.<\/p>\n<p>Os ve\u00edculos, marca Scania, anos 1988 e 1991, frutos de apreens\u00f5es da Receita, ser\u00e3o utilizados no Programa de Microcr\u00e9dito, em parceria com o Sebrae, e em programas de inclus\u00e3o digital nas escolas municipais, com o objetivo de expandir os dois segmentos junto \u00e0 comunidade dos bairros.<\/p>\n<p>Para Eduardo, a unidade m\u00f3vel \u00e9 fundamental para despertar o esp\u00edrito empreendedor nas pessoas. \u201c\u00c9 um instrumento de aproxima\u00e7\u00e3o com a comunidade, dando acesso \u00e0s pessoas que t\u00eam dificuldade de se deslocar dos bairros para o centro\u201d, disse.<\/p>\n<p>Na ocasi\u00e3o, a gerente Regional do Sebrae Ros\u00e2ni Ribeiro apresentou ao prefeito o projeto \u201cLinha da Pequena Empresa\u201d, desenvolvido dentro de um \u00f4nibus, devidamente adaptado para atender os microempreendedores individuais de outras localidades da cidade . Ela explicou que, atrav\u00e9s desta a\u00e7\u00e3o, o Sebrae e as entidades parceiras levam orienta\u00e7\u00f5es sobre a formaliza\u00e7\u00e3o para obter uma linha de microcr\u00e9dito, concess\u00e3o de alvar\u00e1s, capacita\u00e7\u00f5es em gest\u00e3o empresarial, impress\u00e3o de documentos e outras informa\u00e7\u00f5es importantes para beneficiar no desenvolvimento das empresas.<\/p>\n<p>De acordo com o superintendente de Economia Popular da Sdet, Darci Ferreira, o Programa de Microcr\u00e9dito ajuda na formaliza\u00e7\u00e3o de empresas em Pelotas. \u201cO programa \u00e9 um \u2018case\u2019 de sucesso, at\u00e9 agora j\u00e1 movimentou cerca de R$ 17 milh\u00f5es, atrav\u00e9s de 3.820 empreendedores\u201d, destacou.<\/p>\n<p>Ao final do encontro, o delegado Ricardo de Souza Moreira falou do projeto \u201cEduca\u00e7\u00e3o Fiscal\u201d, que d\u00e1 escalrecimentos ao cidad\u00e3o sobre a \u00e1rea fiscal, como a aduaneira. \u201cO objetivo \u00e9 esclarecer, por meio de palestras e semin\u00e1rios, como as pessoas podem atuar de forma regular\u201d, disse.<\/p>\n<p>Tamb\u00e9m participaram do encontro, o secret\u00e1rio de Desenvolvimento Econ\u00f4mico e Turismo, Fernando Estima, a secret\u00e1ria de Gest\u00e3o da Cidade e Mobilidade Urbana, Joseane Almeida, o chefe do Setor de Patrim\u00f4nio e Log\u00edstica da Receita, Paulo Eduardo G. da Costa, a representante da Educa\u00e7\u00e3o Fiscal Mara R. Colomby e a auditora Assistencial do Gabinete da Delegacia da Receita Dulce de Paula.<\/p>\n<p><em>Fonte: Prefeitura Pelotas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal de Pelotas doou dois \u00f4nibus para a prefeitura de Pelotas. O termo de doa\u00e7\u00e3o foi formalizado no final da tarde da \u00faltima ter\u00e7a-feira (18), entre o prefeito Eduardo Leite e o delegado do \u00f3rg\u00e3o Ricardo de Souza Moreira. Os ve\u00edculos, marca Scania, anos 1988 e 1991, frutos de apreens\u00f5es da Receita, ser\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-886","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/886\/revisions"}],"predecessor-version":[{"id":887,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/886\/revisions\/887"}],"wp:attachment":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}