{"id":89,"date":"2012-02-17T18:40:09","date_gmt":"2012-02-17T18:40:09","guid":{"rendered":"http:\/\/www.encontrapelotas.com.br\/noticias\/?p=89"},"modified":"2013-08-16T14:16:54","modified_gmt":"2013-08-16T14:16:54","slug":"sanep-assina-contrato-para-transbordo-dos-residuos-solidos-em-pelotas","status":"publish","type":"post","link":"https:\/\/www.encontrapelotas.com.br\/noticias\/sanep-assina-contrato-para-transbordo-dos-residuos-solidos-em-pelotas\/","title":{"rendered":"Sanep assina contrato para transbordo dos res\u00edduos s\u00f3lidos em Pelotas"},"content":{"rendered":"<p>A Empresa Meio Oeste Ambiental Ltda, de Santa Catarina, deve iniciar em 30 dias a opera\u00e7\u00e3o da Esta\u00e7\u00e3o de Transbordo, transporte e disposi\u00e7\u00e3o final de uma m\u00e9dia di\u00e1ria de 295 toneladas de res\u00edduos s\u00f3lidos da Cidade de Pelotas.<\/p>\n<p>O contrato foi assinado na manh\u00e3 desta quinta-feira (16) no Pa\u00e7o Municipal, e a ordem de servi\u00e7o deve ser expedida ainda hoje pelo Sanep. Participaram do ato o vice-prefeito Fabr\u00edcio Tavares, o diretor-presidente do Sanep, Ubiratan Anselmo, o diretor regional da Meio Oeste, Rubem Moritz, e diretores da empresa.<\/p>\n<p>\u201cEste contrato com a empresa vencedora da licita\u00e7\u00e3o resolve o problema imediato que t\u00ednhamos &#8211; a destina\u00e7\u00e3o final dos res\u00edduos s\u00f3lidos\u201d-, afirma o vice-prefeito, acrescentando que o atual aterro sanit\u00e1rio j\u00e1 est\u00e1 saturado, tendo, inclusive recebido intima\u00e7\u00e3o da Fepam para n\u00e3o mais utiliza\u00e7\u00e3o da \u00e1rea.<\/p>\n<p>Fonte: <em>Prefeitura Municipal de Pelotas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Empresa Meio Oeste Ambiental Ltda, de Santa Catarina, deve iniciar em 30 dias a opera\u00e7\u00e3o da Esta\u00e7\u00e3o de Transbordo, transporte e disposi\u00e7\u00e3o final de uma m\u00e9dia di\u00e1ria de 295 toneladas de res\u00edduos s\u00f3lidos da Cidade de Pelotas. O contrato foi assinado na manh\u00e3 desta quinta-feira (16) no Pa\u00e7o Municipal, e a ordem de servi\u00e7o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[15],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-pelotas"],"_links":{"self":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":4,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":982,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/posts\/89\/revisions\/982"}],"wp:attachment":[{"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapelotas.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}